{"id":15676,"date":"2026-07-02T16:30:36","date_gmt":"2026-07-02T14:30:36","guid":{"rendered":"https:\/\/www.realmurcia.es\/tiendaonline\/?post_type=product&#038;p=15676"},"modified":"2026-07-15T13:01:14","modified_gmt":"2026-07-15T11:01:14","slug":"camiseta-1a-equipacion-abonado","status":"publish","type":"product","link":"https:\/\/www.realmurcia.es\/tiendaonline\/producto\/camiseta-1a-equipacion-abonado\/","title":{"rendered":"CAMISETA 1\u00aa EQUIPACI\u00d3N 27-26 ABONADO"},"content":{"rendered":"<div><strong>Ficha T\u00e9cnica del Producto<\/strong><\/div>\n<div><\/div>\n<div>&#8211; Composici\u00f3n y Tejido: 100% poli\u00e9ster. Tejido t\u00e9cnico ligero tintado de alta calidad, dise\u00f1ado para el m\u00e1ximo confort y durabilidad.<\/div>\n<div>&#8211; Tecnolog\u00eda de Transpirabilidad: Innovadora trama microperforada (ondas y motivos florales huertanos) integrada en el tejido para una evacuaci\u00f3n \u00f3ptima del sudor y mayor frescura.<\/div>\n<div>&#8211; Color y Est\u00e9tica: Grana intenso de profundidad crom\u00e1tica reactiva a la luz, ofreciendo un contraste sofisticado y puro.<\/div>\n<div>&#8211; Cuello y Mangas: Elegante cuello estilo polo con escote en \u00abV\u00bb. Tanto el cuello como las mangas cuentan con acabado el\u00e1stico para un ajuste perfecto, adornados con una exclusiva tira tricolor (oro, blanco, oro).<\/div>\n<div>&#8211; Escudo Oficial: Dise\u00f1o cl\u00e1sico a todo color, cosido de forma solemne y directa sobre el tejido grana.<\/div>\n<div>&#8211; Detalles Exclusivos (Edici\u00f3n Oro):<\/div>\n<div>&#8211; Logotipos de Joma y perfilado del patrocinador principal en color oro.<\/div>\n<div>&#8211; Interior del cuello con dise\u00f1o inspirado en el chaleco huertano (estampaci\u00f3n dorada) y el lema \u00abComo Una Sola Alma\u00bb.<\/div>\n<div>&#8211; Inscripci\u00f3n \u00abCoraz\u00f3n Pimentonero\u00bb en la manga.<\/div>\n<div>&#8211; Inscripci\u00f3n \u00abReal Murcia CF\u00bb en la parte posterior del cuello.<\/div>\n<div>&#8211; Corte: Slim Fit. Ajuste aerodin\u00e1mico y ce\u00f1ido al cuerpo, ideal tanto para el alto rendimiento deportivo como para el uso casual.<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Condici\u00f3n Precio Abonado.<br \/>\nEl club comprobar\u00e1 que se cumpla la condici\u00f3n de abonado en el momento de compra. En caso contrario, el comprador no podr\u00e1 retirar el producto hasta regularizar la situaci\u00f3n. En caso de devoluci\u00f3n se realizar\u00e1 descontando los gastos generados.<br \/>\n<strong><br \/>\nPromoci\u00f3n exclusiva para abonados 2026\/27.<\/strong>\u00a0<strong>Caja met\u00e1lica personalizada GRATIS con la compra de tu camiseta presentando tu ticket de compra en nuestra Tienda Estadio. S\u00f3lo recogida en tienda.\u00a0<\/strong><strong>Promoci\u00f3n v\u00e1lida hasta el 31 de agosto.<\/strong><\/p>\n<div>\n<div><strong>Camiseta Oficial 1\u00aa Equipaci\u00f3n Real Murcia C.F. 2026\/2027<\/strong><\/div>\n<div>Viste la esencia pimentonera en su m\u00e1xima pureza.<\/div>\n<div>La Primera Equipaci\u00f3n del Real Murcia C.F. para la temporada 26\/27 rinde homenaje a nuestra identidad con un dise\u00f1o profundamente grana, intenso y decidido. En una fusi\u00f3n perfecta entre innovaci\u00f3n deportiva y herencia cultural, el tejido esconde una sutil trama de ondas y motivos florales inspirados en los chalecos del Bando de la Huerta. Este patr\u00f3n no solo exalta la profundidad crom\u00e1tica de la prenda con el reflejo de la luz, sino que act\u00faa como un sistema de microperforado para ofrecer un rendimiento superior en el campo.<\/div>\n<div>Elevada por elegantes detalles en oro que coronan nuestro orgullo y un cuello estilo polo se\u00f1orial, con cuello interior tramado con estampaciones de chaleco clasica de el \u00abEl bando de la huerta\u00bb. Adem\u00e1s esta el\u00e1stica muestra en su parte frontal inferior el latido de toda una Regi\u00f3n: el lema \u00abComo Una Sola Alma\u00bb. No es solo nuestra piel; es el s\u00edmbolo eterno de nuestra pertenencia.<\/div>\n<div><\/div>\n<\/div>\n","protected":false},"featured_media":15665,"template":"","meta":{"_mo_disable_npp":"","site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"default","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"_joinchat":[]},"product_brand":[],"product_cat":[303,307],"product_tag":[],"class_list":["post-15676","product","type-product","status-publish","has-post-thumbnail","product_cat-coleccion26-27","product_cat-equipaciones-de-juego-26-27","desktop-align-center","tablet-align-center","mobile-align-center","ast-product-gallery-layout-horizontal-slider","ast-product-single-variable","ast-product-tabs-layout-vertical","first","instock","taxable","shipping-taxable","purchasable","product-type-variable","has-default-attributes"],"exclude_global_add_ons":false,"addons":[{"name":"-","type":"custom_text","position":0,"required":false,"title_format":"label","default":"","description_enable":false,"description":"","placeholder_enable":false,"placeholder":"","display":"select","restrictions_type":"any_text","adjust_price":false,"price":"","price_type":"flat_fee","restrictions":false,"min":"0","max":"0","options":[],"id":1752108915},{"name":"\u00bfQuieres a\u00f1adir parche de la RFEF?","type":"checkbox","position":1,"required":true,"title_format":"label","default":"","description_enable":false,"description":"","placeholder_enable":false,"placeholder":"","display":"select","restrictions_type":"any_text","adjust_price":false,"price":"","price_type":"flat_fee","restrictions":false,"min":"0","max":"0","options":[{"label":"SI","price":"6","price_type":"flat_fee","image":0,"visibility":true},{"label":"NO","price":"","price_type":"flat_fee","image":0,"visibility":true}],"id":1752108895},{"name":"\u00bfQuieres a\u00f1adir n\u00famero a la camiseta?","type":"custom_text","position":2,"required":false,"title_format":"label","default":"","description_enable":true,"description":"La realizaci\u00f3n de la serigrafia afectar\u00e1 al plazo de entrega de tu pedido.","placeholder_enable":false,"placeholder":"","display":"select","restrictions_type":"only_numbers","adjust_price":true,"price":"9.50","price_type":"flat_fee","restrictions":true,"min":"0","max":"2","options":[],"id":1752108893},{"name":"\u00bfQuieres a\u00f1adir nombre a la camiseta?","type":"custom_text","position":3,"required":false,"title_format":"label","default":"","description_enable":true,"description":"Los nombres que resulten ofensivos o atenten contra la integridad moral del club podr\u00e1n ser rechazados. La realizaci\u00f3n de la serigrafia afectar\u00e1 al plazo de entrega de tu pedido.\r\nLas camisetas serigrafiadas no se pondr\u00e1n devolver ni cambiar.","placeholder_enable":false,"placeholder":"","display":"radiobutton","restrictions_type":"any_text","adjust_price":true,"price":"9.50","price_type":"flat_fee","restrictions":true,"min":"0","max":"12","options":[],"id":1752108894}],"_links":{"self":[{"href":"https:\/\/www.realmurcia.es\/tiendaonline\/wp-json\/wp\/v2\/product\/15676","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.realmurcia.es\/tiendaonline\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.realmurcia.es\/tiendaonline\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.realmurcia.es\/tiendaonline\/wp-json\/wp\/v2\/media\/15665"}],"wp:attachment":[{"href":"https:\/\/www.realmurcia.es\/tiendaonline\/wp-json\/wp\/v2\/media?parent=15676"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.realmurcia.es\/tiendaonline\/wp-json\/wp\/v2\/product_brand?post=15676"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.realmurcia.es\/tiendaonline\/wp-json\/wp\/v2\/product_cat?post=15676"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.realmurcia.es\/tiendaonline\/wp-json\/wp\/v2\/product_tag?post=15676"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}